{"id":955,"date":"2025-06-28T11:17:22","date_gmt":"2025-06-28T11:17:22","guid":{"rendered":"https:\/\/hosana.digital\/site\/?p=955"},"modified":"2025-07-09T19:52:18","modified_gmt":"2025-07-09T22:52:18","slug":"rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja","status":"publish","type":"post","link":"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/","title":{"rendered":"Rotina administrativa sem papel: como digitalizar os processos da igreja"},"content":{"rendered":"\n<p>Se voc\u00ea cuida da secretaria da igreja ou mexe com boletim, cadastro e relat\u00f3rio, senta que hoje o assunto vai mudar seu minist\u00e9rio. Vamos conversar sobre <strong>como tirar o papel da mesa e colocar ordem na casa com um sistema online para igrejas<\/strong>.<\/p>\n\n\n\n<p>Sim, eu sei&#8230; tem gente que ainda quer fazer controle no caderno. Mas deixa eu te contar: isso gasta tempo, d\u00e1 erro e ningu\u00e9m entende aquela letra de m\u00e9dico do di\u00e1cono. E c\u00e1 entre n\u00f3s: a igreja cresceu, os membros multiplicaram, o fluxo aumentou&#8230; N\u00e3o d\u00e1 mais pra ficar no bloquinho!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#Por_que_digitalizar_os_processos_administrativos_da_igreja\" >Por que digitalizar os processos administrativos da igreja?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#O_que_muda_quando_a_gestao_sai_do_papel\" >O que muda quando a gest\u00e3o sai do papel?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#Principais_areas_que_podem_ser_digitalizadas\" >Principais \u00e1reas que podem ser digitalizadas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#Beneficios_de_usar_um_sistema_online_para_igrejas\" >Benef\u00edcios de usar um sistema online para igrejas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#Mas_e_a_seguranca_dos_dados_da_igreja\" >Mas e a seguran\u00e7a dos dados da igreja?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#Dicas_para_comecar_a_digitalizacao_da_igreja\" >Dicas para come\u00e7ar a digitaliza\u00e7\u00e3o da igreja<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#A_transformacao_comeca_com_decisao\" >A transforma\u00e7\u00e3o come\u00e7a com decis\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#FAQ_%E2%80%93_Perguntas_frequentes\" >FAQ \u2013 Perguntas frequentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#1_O_sistema_online_para_igrejas_funciona_sem_internet\" >1. O sistema online para igrejas funciona sem internet?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#2_Posso_usar_pelo_celular\" >2. Posso usar pelo celular?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#3_E_dificil_de_usar\" >3. \u00c9 dif\u00edcil de usar?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#4_Os_dados_ficam_seguros\" >4. Os dados ficam seguros?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/hosana.digital\/site\/rotina-administrativa-sem-papel-como-digitalizar-os-processos-da-igreja\/#5_Qual_o_custo\" >5. Qual o custo?<\/a><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Por_que_digitalizar_os_processos_administrativos_da_igreja\"><\/span>Por que digitalizar os processos administrativos da igreja?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A rotina de uma igreja \u00e9 quase como uma empresa: tem entrada e sa\u00edda de dinheiro, pessoas chegando, dados sendo atualizados o tempo todo.<\/p>\n\n\n\n<p>Quando fazemos tudo no papel, o risco de perder informa\u00e7\u00f5es, errar datas ou esquecer compromissos aumenta muito.<\/p>\n\n\n\n<p><strong>Usar um sistema online para igrejas evita retrabalho e facilita a gest\u00e3o dos dados dos membros, visitantes e finan\u00e7as.<\/strong><\/p>\n\n\n\n<p>Com tudo armazenado na nuvem, a gente acessa de qualquer lugar, pelo celular, tablet ou computador. Basta ter internet.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_muda_quando_a_gestao_sai_do_papel\"><\/span>O que muda quando a gest\u00e3o sai do papel?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Vou te dar um panorama de quem j\u00e1 vive essa realidade com sistema digital:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nada se perde:<\/strong> todos os dados ficam salvos e organizados.<\/li>\n\n\n\n<li><strong>Mais agilidade:<\/strong> precisa saber quem faltou no culto? Em segundos voc\u00ea acessa.<\/li>\n\n\n\n<li><strong>Transpar\u00eancia:<\/strong> relat\u00f3rios de entradas e sa\u00eddas prontos com poucos cliques.<\/li>\n\n\n\n<li><strong>Comunica\u00e7\u00e3o eficiente:<\/strong> envia avisos por e-mail, SMS ou app em massa.<\/li>\n<\/ul>\n\n\n\n<p>A igreja fica moderna, organizada e com tudo debaixo de controle. Quem mexe com a gest\u00e3o sente a diferen\u00e7a j\u00e1 na primeira semana.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Principais_areas_que_podem_ser_digitalizadas\"><\/span>Principais \u00e1reas que podem ser digitalizadas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Voc\u00ea pode come\u00e7ar aos poucos, mas o ideal \u00e9 levar toda a estrutura da administra\u00e7\u00e3o pra dentro de um <strong>sistema online para igrejas<\/strong>.<\/p>\n\n\n\n<p>Veja o que d\u00e1 pra organizar de forma digital:<\/p>\n\n\n\n<p><strong>1. Cadastro de membros<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dados pessoais e endere\u00e7o<\/li>\n\n\n\n<li>Minist\u00e9rio ou fun\u00e7\u00e3o na igreja<\/li>\n\n\n\n<li>Hist\u00f3rico de discipulado e batismo<\/li>\n\n\n\n<li>Participa\u00e7\u00e3o em c\u00e9lulas e eventos<\/li>\n<\/ul>\n\n\n\n<p><strong>2. Controle financeiro<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lan\u00e7amento de d\u00edzimos e ofertas<\/li>\n\n\n\n<li>Categorias de despesas<\/li>\n\n\n\n<li>Relat\u00f3rios financeiros por m\u00eas ou evento<\/li>\n\n\n\n<li>Presta\u00e7\u00e3o de contas automatizada<\/li>\n<\/ul>\n\n\n\n<p><strong>3. Escalas e volunt\u00e1rios<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Escalas de minist\u00e9rios (louvor, recep\u00e7\u00e3o, intercess\u00e3o etc.)<\/li>\n\n\n\n<li>Controle de presen\u00e7a e faltas<\/li>\n\n\n\n<li>Substitui\u00e7\u00f5es e comunica\u00e7\u00e3o direta com a equipe<\/li>\n<\/ul>\n\n\n\n<p><strong>4. Comunica\u00e7\u00e3o com os membros<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avisos de cultos e eventos<\/li>\n\n\n\n<li>Envio de devocionais<\/li>\n\n\n\n<li>Recados urgentes por WhatsApp ou notifica\u00e7\u00e3o no app<\/li>\n<\/ul>\n\n\n\n<p><strong>5. Agenda da igreja<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Marca\u00e7\u00e3o de cultos, eventos e reuni\u00f5es<\/li>\n\n\n\n<li>Agendamento de visitas e batismos<\/li>\n\n\n\n<li>Reserva de espa\u00e7o (salas, audit\u00f3rio, vans)<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Beneficios_de_usar_um_sistema_online_para_igrejas\"><\/span>Benef\u00edcios de usar um sistema online para igrejas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>N\u00e3o \u00e9 s\u00f3 uma quest\u00e3o de praticidade, mas tamb\u00e9m de cuidado com o que Deus colocou nas suas m\u00e3os.<\/p>\n\n\n\n<p><strong>Com um sistema bem implantado, a igreja cresce com estrutura e sa\u00fade.<\/strong> Olha s\u00f3 o que muda:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Menos papelada acumulada e mais espa\u00e7o f\u00edsico livre<\/strong><\/li>\n\n\n\n<li><strong>Equipe pastoral informada com relat\u00f3rios prontos<\/strong><\/li>\n\n\n\n<li><strong>Membros mais bem assistidos com dados organizados<\/strong><\/li>\n\n\n\n<li><strong>Maior transpar\u00eancia nas finan\u00e7as<\/strong><\/li>\n<\/ul>\n\n\n\n<p>O l\u00edder deixa de depender do &#8220;achismo&#8221; e come\u00e7a a tomar decis\u00f5es com base em dados reais.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mas_e_a_seguranca_dos_dados_da_igreja\"><\/span>Mas e a seguran\u00e7a dos dados da igreja?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ah, irm\u00e3o&#8230; esse \u00e9 um ponto chave!<\/p>\n\n\n\n<p><strong>Os sistemas s\u00e9rios usam criptografia, backups autom\u00e1ticos e seguem a LGPD (Lei Geral de Prote\u00e7\u00e3o de Dados).<\/strong><\/p>\n\n\n\n<p>Nada de caderno esquecido na sala, ou planilha perdida no computador da irm\u00e3 do louvor. Tudo protegido e com acesso autorizado apenas a quem precisa.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dicas_para_comecar_a_digitalizacao_da_igreja\"><\/span>Dicas para come\u00e7ar a digitaliza\u00e7\u00e3o da igreja<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Se sua igreja ainda t\u00e1 no papel, vou te ajudar a sair dessa terra do Egito e entrar na Cana\u00e3 digital:<\/p>\n\n\n\n<p><strong>1. Escolha um bom sistema online para igrejas<\/strong><\/p>\n\n\n\n<p>Pesquise, teste, veja o que se encaixa no seu perfil. O Hosana.digital possui um dos mais completos ecosistemas de gest\u00e3o de igrejas com plataforma+app!<\/p>\n\n\n\n<p><strong>2. Treine a equipe<\/strong><\/p>\n\n\n\n<p>Chama a equipe da tesouraria, da secretaria, do louvor. Ensina todo mundo a usar.<\/p>\n\n\n\n<p><strong>3. Comece pelo b\u00e1sico<\/strong><\/p>\n\n\n\n<p>N\u00e3o precisa digitalizar tudo em um dia. Comece com cadastro de membros e o financeiro.<\/p>\n\n\n\n<p><strong>4. Mantenha os dados atualizados<\/strong><\/p>\n\n\n\n<p>Sem atualiza\u00e7\u00e3o, o sistema vira s\u00f3 mais uma bagun\u00e7a digital. Coloca disciplina na gest\u00e3o!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_transformacao_comeca_com_decisao\"><\/span>A transforma\u00e7\u00e3o come\u00e7a com decis\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A tecnologia n\u00e3o \u00e9 inimiga da igreja. Ela \u00e9 ferramenta. E quando bem usada, ela ajuda o Reino a crescer com qualidade.<\/p>\n\n\n\n<p><strong>Usar um sistema online para igrejas \u00e9 abra\u00e7ar uma gest\u00e3o mais moderna, transparente e funcional.<\/strong><\/p>\n\n\n\n<p>A sua secretaria, o seu pastor e toda a membresia agradecem. Porque uma igreja organizada serve melhor, discipula melhor e alcan\u00e7a mais vidas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"FAQ_%E2%80%93_Perguntas_frequentes\"><\/span>FAQ \u2013 Perguntas frequentes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1751108882016\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"1_O_sistema_online_para_igrejas_funciona_sem_internet\"><\/span><strong>1. O sistema online para igrejas funciona sem internet?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>A maioria precisa de conex\u00e3o, para garantir integridade\/sincronismo das informa\u00e7\u00f5es inseridas.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1751108898907\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"2_Posso_usar_pelo_celular\"><\/span><strong>2. Posso usar pelo celular?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Sim! Sistemas como o Hosana.digital possuem um aplicativo com op\u00e7\u00f5es e servi\u00e7os direcionados para os membros de igreja.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1751108907746\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"3_E_dificil_de_usar\"><\/span><strong>3. \u00c9 dif\u00edcil de usar?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>N\u00e3o. A maioria tem interface simples e intuitiva. Com um treinamento r\u00e1pido, qualquer irm\u00e3ozinho aprende.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1751108914202\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"4_Os_dados_ficam_seguros\"><\/span><strong>4. Os dados ficam seguros?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Sim. Bons sistemas usam criptografia e backup autom\u00e1tico na nuvem. O Hosana.digital possui uma op\u00e7\u00e3o de backup manual, feita pelo pr\u00f3prio cliente<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1751108919938\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"5_Qual_o_custo\"><\/span><strong>5. Qual o custo?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Depende do tamanho da igreja e das fun\u00e7\u00f5es. O Hosana.digital possui op\u00e7\u00f5es com ou sem aplicativo, com planos a partir de R$ 60,00<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea cuida da secretaria da igreja ou mexe com boletim, cadastro e relat\u00f3rio, senta que hoje o assunto vai mudar seu minist\u00e9rio. Vamos conversar [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[29,519,523,525,26,527,521,520,524,522,517,495,526,497,518],"class_list":["post-955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-administracao-eclesiastica","tag-cadastro-de-membros","tag-controle-de-dizimos","tag-financas-cristas","tag-gestao-de-igrejas","tag-gestao-de-voluntarios","tag-igreja-digital","tag-lgpd-na-igreja","tag-organizacao-eclesiastica","tag-rotina-sem-papel","tag-secretaria-de-igreja","tag-sistema-online-para-igrejas","tag-sistema-para-ministerios","tag-software-para-igrejas","tag-tesouraria-evangelica"],"_links":{"self":[{"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/posts\/955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/comments?post=955"}],"version-history":[{"count":7,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/posts\/955\/revisions"}],"predecessor-version":[{"id":995,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/posts\/955\/revisions\/995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/media\/197"}],"wp:attachment":[{"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/media?parent=955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/categories?post=955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hosana.digital\/site\/wp-json\/wp\/v2\/tags?post=955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}